{"id":9779,"date":"2017-01-31T13:08:37","date_gmt":"2017-01-31T13:08:37","guid":{"rendered":"https:\/\/montefiore.eu\/montefiore-se-distingue-en-performance\/"},"modified":"2017-01-31T13:08:37","modified_gmt":"2017-01-31T13:08:37","slug":"montefiore-se-distingue-en-performance","status":"publish","type":"post","link":"https:\/\/montefiore.eu\/en\/montefiore-se-distingue-en-performance\/","title":{"rendered":"Montefiore se distingue en performance"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221; sticky_content_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-2&#8243; icon_family=&#8221;none&#8221; text=&#8221;VERSION PDF&#8221; url=&#8221;\/wp-content\/uploads\/2023\/12\/2017-01-30-Montefiore-se-distingue-en-performance.pdf&#8221;][nectar_global_section id=&#8221;6885&#8243;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221;]<strong>Montefiore se distingue en performance<\/strong><\/p>\n<p>L&#8217;investisseur sp\u00e9cialis\u00e9 dans les PME de services g\u00e9rant plus d&#8217;1 Md\u20ac finit comme 1er fonds LBO fran\u00e7ais dans le classement de Preqin. MontefioreInvestment a connu une ann\u00e9e 2016 particuli\u00e8rement active sur tous les fronts, lev\u00e9e de fonds, investissements et cessions. L&#8217;investisseur sp\u00e9cialis\u00e9 dans les PME de services fran\u00e7aises a atteint, en seulement trois mois, le hard cap de son quatri\u00e8me fonds &#8211; MontefioreInvestment IV &#8211; \u00e0 420 M\u20ac via un seul closing en Juillet 2016 (lire ci dessous) lui permettant de d\u00e9passer 1 Md\u20ac d&#8217;actifs sous gestion. Les souscripteurs proviennent \u00e0 40 % de France, \u00e0 30% de l&#8217;Europe et \u00e0 30% de l&#8217;international (Am\u00e9rique du Nord, Asie et Australie). Il avait comme objectif d&#8217;atteindre de r\u00e9colter 350 M\u20ac contre 240 M\u20ac pour la pr\u00e9c\u00e9dente g\u00e9n\u00e9ration. Actuellement, le nouveau v\u00e9hicule n&#8217;a pas encore de participations. Des discussions seraient, d&#8217;ores et d\u00e9j\u00e0, engag\u00e9es, pour de nouveaux investissements dans le premier semestre 2017. MontefioreInvestment III a r\u00e9alis\u00e9 ses deux derni\u00e8res op\u00e9rations, en 2016. Il a particip\u00e9, majoritairement aux cot\u00e9s de Vente-priv\u00e9e.com, \u00e0 la lev\u00e9e de fonds de 20 M\u20ac de Misterfly, agence de voyages en ligne n\u00e9e en octobre 2014 par l&#8217;initiative du duo de fondateurs de Go Voyages (lire ci-dessous).\u00a0 Quatri\u00e8me fonds europ\u00e9en de buy-out selon PrequinLe fonds d&#8217;investissement a, \u00e9galement, pris une participation majoritaire -51 % &#8211; dans Isabel Marrant la valorisant plus de 300 M\u20ac (lire ci-dessous). Au sein de son portefeuille, Montefiore Investment a particip\u00e9 \u00e0 la r\u00e9alisation d&#8217;une dizaine d&#8217;acquisitions compl\u00e9mentaires. Sur l&#8217;exercice 2016, l&#8217;investisseur a clos\u00e9 q uatre cessions dont la vente d&#8217;Avenir Sant\u00e9 g\u00e9n\u00e9rant un chiffre d&#8217;affaires de 55 M\u20ac \u00e0 C2S, groupe rh\u00f4nalpin de cliniques priv\u00e9es en LBO avec Bridge point Development Capital (lire ci-dessous). Toutes ces performances l&#8217;ont amen\u00e9 \u00e0 int\u00e9grer le classement des Consistent Performers dans la cat\u00e9gorie buy-out r\u00e9alis\u00e9, tous les six mois, par la base de donn\u00e9es Preqin. Cette derni\u00e8re regarde la performance de tous les fonds d&#8217;une m\u00eame soci\u00e9t\u00e9 de gestion sur\u00a0 plusieurs ann\u00e9es. Pr\u00e9sid\u00e9 par Eric Bismuth (photo ci-contre), Montefiore Investment se classe quatri\u00e8me ex-aequo au niveau europ\u00e9en et premier fran\u00e7ais. \u201c<em>L&#8217;ann\u00e9e 2016 a \u00e9t\u00e9, pour nous, l&#8217;ann\u00e9e de la continuit\u00e9 dans notre strat\u00e9gie d&#8217;investissement mais \u00e9galement celle de l&#8217;acc\u00e9l\u00e9ration notamment avec la lev\u00e9e r\u00e9ussie de notre nouveau fonds<\/em>\u201c, conclut le pr\u00e9sident en pr\u00e9cisant que l&#8217;ann\u00e9e 2017 sera plus riche en investissements qu&#8217;en cessions. Lire aussi: C2S gagne la Bourgogne Franche-Comt\u00e9 (30\/08\/2016) Closing final pour MontefioreInvestment IV (27\/07\/2016) Isabel Marant d\u00e9file avec un fonds (27\/06\/2016) MisterFly d\u00e9colle avec un fonds (22\/06\/2016)[\/vc_column_text][vc_row_inner disable_element=&#8221;yes&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;30&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;1px&#8221; column_border_color=&#8221;#9e1b0d&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]\u00c0 propos de Montefiore Investment<\/p>\n<p>Cr\u00e9\u00e9 en 2005, Montefiore Investment est l\u2019investisseur de r\u00e9f\u00e9rence dans les PME et ETI de services en France. Fort d\u2019une \u00e9quipe de 50 collaborateurs, et en s\u2019appuyant sur son expertise sectorielle et son savoir-faire, la soci\u00e9t\u00e9 accompagne avec succ\u00e8s les entreprises dans leurs projets de croissance et de d\u00e9veloppement. Montefiore Investment a d\u00e9montr\u00e9 sa capacit\u00e9 \u00e0 transformer les ETI et PME en v\u00e9ritables champions europ\u00e9ens. Ses performances lui ont permis de s\u2019imposer comme une r\u00e9f\u00e9rence incontournable du capital investissement sur le mid-market. Bas\u00e9 \u00e0 Paris et \u00e0 Milan, Montefiore Investment dispose aujourd\u2019hui de 4 milliards d\u2019euros de fonds propres sous gestion et investit des tickets de 20 \u00e0 200 millions d\u2019euros de fonds propres pour financer la croissance durable et rentable de ses participations. Depuis 2021, Montefiore est \u00e9galement actionnaire et partenaire strat\u00e9gique de Starquest, soci\u00e9t\u00e9 de gestion d\u00e9di\u00e9e aux investissements dans les soci\u00e9t\u00e9s innovantes \u00e0 fort impact environnemental (GreenTech).[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner disable_element=&#8221;yes&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;30&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;1px&#8221; column_border_color=&#8221;#9e1b0d&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]\u00c0 propos de Catlante Catamarans<\/p>\n<p>Cr\u00e9\u00e9e en 2003, Catlante Catamarans s&#8217;est hiss\u00e9e au rang de r\u00e9f\u00e9rence en fran\u00e7aise des croisi\u00e8res en catamaran haut de gamme avec \u00e9quipage. A la cabine ou en privatisation, la Compagnie propose des voyages inoubliables \u00e0 bord de catamarans raffin\u00e9s, dans le monde entier, tout en affichant un engagement profond envers les pr\u00e9occupations environnementales et soci\u00e9tales. Les navires, enti\u00e8rement d\u00e9tenus par la Compagnie, sont con\u00e7us et construits sur-mesure afin de r\u00e9pondre aux exigences sp\u00e9cifiques de ce type de croisi\u00e8res, notamment les mod\u00e8les Catlante 600, Catlante 620 et Catlante 720. Chacune de ces croisi\u00e8res est accompagn\u00e9e d\u2019un \u00e9quipage compos\u00e9 de Capitaines exp\u00e9riment\u00e9s et de chefs cuisiniers, qui ont fait la r\u00e9putation de l\u2019entreprise.[\/vc_column_text][nectar_cta btn_style=&#8221;underline&#8221; heading_tag=&#8221;p&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;new_tab&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; link_text=&#8221;catlante-catamarans.com&#8221; url=&#8221;https:\/\/www.catlante-catamarans.com\/&#8221; text=&#8221;Pour en savoir plus :&#8221;][vc_column_text css_animation=&#8221;none&#8221; el_class=&#8221;small red&#8221; css=&#8221;.vc_custom_1698677023785{margin-top: 20px !important;}&#8221;]<strong>CONTACT\u00a0<\/strong>[\/vc_column_text][vc_column_text css_animation=&#8221;none&#8221; el_class=&#8221;small&#8221;]Laur\u00e8ne Pulliat<br \/>\nResponsable communication<br \/>\n<a href=\"mailto:lp@catlante.com\">lp@catlante.com<\/a><br \/>\n06 10 24 07 00[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221;&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[111],"tags":[],"class_list":["post-9779","post","type-post","status-publish","format-standard","category-press-release"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Montefiore se distingue en performance - Montefiore Investment<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/montefiore.eu\/en\/montefiore-se-distingue-en-performance\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Montefiore se distingue en performance - Montefiore Investment\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/montefiore.eu\/en\/montefiore-se-distingue-en-performance\/\" \/>\n<meta property=\"og:site_name\" content=\"Montefiore Investment\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-31T13:08:37+00:00\" \/>\n<meta name=\"author\" content=\"Montefiore\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WeAreBlow\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Montefiore\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/montefiore-se-distingue-en-performance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/montefiore-se-distingue-en-performance\\\/\"},\"author\":{\"name\":\"Montefiore\",\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/#\\\/schema\\\/person\\\/67b7c1f31df6e6d86ea1c4793b97a51c\"},\"headline\":\"Montefiore se distingue en performance\",\"datePublished\":\"2017-01-31T13:08:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/montefiore-se-distingue-en-performance\\\/\"},\"wordCount\":1505,\"articleSection\":[\"Press release\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/montefiore-se-distingue-en-performance\\\/\",\"url\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/montefiore-se-distingue-en-performance\\\/\",\"name\":\"Montefiore se distingue en performance - Montefiore Investment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/#website\"},\"datePublished\":\"2017-01-31T13:08:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/#\\\/schema\\\/person\\\/67b7c1f31df6e6d86ea1c4793b97a51c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/montefiore-se-distingue-en-performance\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/montefiore.eu\\\/en\\\/montefiore-se-distingue-en-performance\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/montefiore-se-distingue-en-performance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Montefiore se distingue en performance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/\",\"name\":\"Montefiore Investment\",\"description\":\"L&#039;investisseur de r\u00e9f\u00e9rence des PME et ETI de services.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/#\\\/schema\\\/person\\\/67b7c1f31df6e6d86ea1c4793b97a51c\",\"name\":\"Montefiore\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef7f344ce0735d89803a1a87d8ba1b0941d46961f140039710ff76a7be36dd04?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef7f344ce0735d89803a1a87d8ba1b0941d46961f140039710ff76a7be36dd04?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef7f344ce0735d89803a1a87d8ba1b0941d46961f140039710ff76a7be36dd04?s=96&d=mm&r=g\",\"caption\":\"Montefiore\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/WeAreBlow\"],\"url\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/author\\\/montefiore\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Montefiore se distingue en performance - Montefiore Investment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/montefiore.eu\/en\/montefiore-se-distingue-en-performance\/","og_locale":"en_US","og_type":"article","og_title":"Montefiore se distingue en performance - Montefiore Investment","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221;...","og_url":"https:\/\/montefiore.eu\/en\/montefiore-se-distingue-en-performance\/","og_site_name":"Montefiore Investment","article_published_time":"2017-01-31T13:08:37+00:00","author":"Montefiore","twitter_card":"summary_large_image","twitter_creator":"@WeAreBlow","twitter_misc":{"Written by":"Montefiore","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/montefiore.eu\/en\/montefiore-se-distingue-en-performance\/#article","isPartOf":{"@id":"https:\/\/montefiore.eu\/en\/montefiore-se-distingue-en-performance\/"},"author":{"name":"Montefiore","@id":"https:\/\/montefiore.eu\/en\/#\/schema\/person\/67b7c1f31df6e6d86ea1c4793b97a51c"},"headline":"Montefiore se distingue en performance","datePublished":"2017-01-31T13:08:37+00:00","mainEntityOfPage":{"@id":"https:\/\/montefiore.eu\/en\/montefiore-se-distingue-en-performance\/"},"wordCount":1505,"articleSection":["Press release"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/montefiore.eu\/en\/montefiore-se-distingue-en-performance\/","url":"https:\/\/montefiore.eu\/en\/montefiore-se-distingue-en-performance\/","name":"Montefiore se distingue en performance - Montefiore Investment","isPartOf":{"@id":"https:\/\/montefiore.eu\/en\/#website"},"datePublished":"2017-01-31T13:08:37+00:00","author":{"@id":"https:\/\/montefiore.eu\/en\/#\/schema\/person\/67b7c1f31df6e6d86ea1c4793b97a51c"},"breadcrumb":{"@id":"https:\/\/montefiore.eu\/en\/montefiore-se-distingue-en-performance\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/montefiore.eu\/en\/montefiore-se-distingue-en-performance\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/montefiore.eu\/en\/montefiore-se-distingue-en-performance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/montefiore.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Montefiore se distingue en performance"}]},{"@type":"WebSite","@id":"https:\/\/montefiore.eu\/en\/#website","url":"https:\/\/montefiore.eu\/en\/","name":"Montefiore Investment","description":"L&#039;investisseur de r\u00e9f\u00e9rence des PME et ETI de services.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/montefiore.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/montefiore.eu\/en\/#\/schema\/person\/67b7c1f31df6e6d86ea1c4793b97a51c","name":"Montefiore","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ef7f344ce0735d89803a1a87d8ba1b0941d46961f140039710ff76a7be36dd04?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ef7f344ce0735d89803a1a87d8ba1b0941d46961f140039710ff76a7be36dd04?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ef7f344ce0735d89803a1a87d8ba1b0941d46961f140039710ff76a7be36dd04?s=96&d=mm&r=g","caption":"Montefiore"},"sameAs":["https:\/\/x.com\/WeAreBlow"],"url":"https:\/\/montefiore.eu\/en\/author\/montefiore\/"}]}},"_links":{"self":[{"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/posts\/9779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/comments?post=9779"}],"version-history":[{"count":0,"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/posts\/9779\/revisions"}],"wp:attachment":[{"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/media?parent=9779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/categories?post=9779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/tags?post=9779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}