{"id":9729,"date":"2018-06-14T10:59:24","date_gmt":"2018-06-14T10:59:24","guid":{"rendered":"https:\/\/montefiore.eu\/les-nouveaux-horizons-de-voyageurs-du-monde\/"},"modified":"2018-06-14T10:59:24","modified_gmt":"2018-06-14T10:59:24","slug":"les-nouveaux-horizons-de-voyageurs-du-monde","status":"publish","type":"post","link":"https:\/\/montefiore.eu\/en\/les-nouveaux-horizons-de-voyageurs-du-monde\/","title":{"rendered":"Les nouveaux horizons de Voyageurs du Monde"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;50px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221; sticky_content_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;1px&#8221; column_border_color=&#8221;rgba(0,0,0,0.13)&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;7243&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; img_link_target=&#8221;_blank&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; img_link=&#8221;\/wp-content\/uploads\/2023\/12\/Les-nouveaux-horizons-de-Voyageurs-du-Monde.pdf&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;norm&#8221;]Alors qu\u2019il approche de la quarantaine \u2013 ses origines remontent \u00e0 1979 \u2013, le groupe Voyageurs du Monde n\u2019a, au fond, jamais aussi bien port\u00e9 son nom. Le sp\u00e9cialiste du voyage sur mesure (avec ses marques Voyageurs du Monde et Comptoir des Voyages) et du voyage aventure (avec, entre autres, Terres d\u2019Aventure, Nomade Aventure et Allibert), rejoint en effet \u00e0 grands pas le petit cercle des g\u00e9ants fran\u00e7ais de dimension internationale dans l\u2019univers du voyage ou du tourisme. Des poids lourds \u00f4 combien embl\u00e9matiques s\u2019agissant de Club Med, du Groupe Pierre &amp; Vacances -Center Parcs ou m\u00eame d\u2019AccorHotels.<\/p>\n<p>A c\u00f4t\u00e9 d\u2019eux, Voyageurs du Monde fait figure de poids l\u00e9ger. Pourtant, sa taille, 427 millions d\u2019euros de chiffre d\u2019affaires en 2017, ne l\u2019emp\u00eache pas d\u2019avoir une strat\u00e9gie<br \/>\ninternationale audacieuse. Dans un secteur du voyage \u00e0 forfait encore atomis\u00e9 et<br \/>\nrenouant avec la reprise apr\u00e8s une d\u00e9cennie de turbulences pour cause, notamment, de crise \u00e9conomique et d\u2019incidences du printemps arabe, Voyageurs du Monde a confirm\u00e9, l\u2019an dernier, la pertinence de son positionnement et l\u2019efficacit\u00e9 de son mod\u00e8le \u00e9conomique en enregistrant des r\u00e9sultats record. Il a aussi chang\u00e9 de statut, passant de num\u00e9ro un de ses segments de march\u00e9 \u00e0 champion national acc\u00e9l\u00e9rant la cadence \u00e0 l\u2019\u00e9tranger. Ainsi, la part de ses revenus r\u00e9alis\u00e9s \u00e0 l\u2019international a bondi de 10 points pour atteindre 21 %, \u00e0 la suite de l\u2019acquisition, en 2017, de deux tour-op\u00e9rateurs anglais Original Travel et KE Adventure Travel. Avec ces sp\u00e9cialistes respectivement du sur-mesure et du voyage aventure,<br \/>\nle voyagiste va pouvoir d\u00e9sormais d\u00e9velopper \u00e0 l\u2019international ses deux grands<br \/>\nm\u00e9tiers.<\/p>\n<p><strong>Histoire collective<\/strong><\/p>\n<p>Ce mouvement strat\u00e9gique, qui a tout de la double op\u00e9ration \u00ab industrielle \u00bb, constitue clairement une nouvelle donne. Voyageurs du Monde, qui avait commenc\u00e9 \u00e0 cultiver une client\u00e8le \u00e9trang\u00e8re francophone, a d\u00e9sormais la voie d\u2019acc\u00e8s au vaste monde anglophone. En filigrane, ce changement de statut pourrait faire office de second tome d\u2019une histoire collective m\u00ealant amiti\u00e9 et entrepreneuriat. Car Voyageurs du Monde, c\u2019est d\u2019abord une aventure humaine<br \/>\navec un triumvirat de managers actionnaires majoritaires sans \u00e9quivalent, avec son<br \/>\nPDG, Jean-Fran\u00e7ois Rial, et ses deux comp\u00e8res directeurs g\u00e9n\u00e9raux d\u00e9l\u00e9gu\u00e9s, Alain<br \/>\nCapestan et Lionel Habasque. Une \u00ab dream team \u00bb qui marie rentabilit\u00e9 et engagements soci\u00e9taux.<\/p>\n<p>Le trio \u2013 une \u00ab bande des cinq \u00bb en r\u00e9alit\u00e9, car deux autres personnes ont eu un r\u00f4le<br \/>\nclef dans cette aventure collective \u2013 prend. forme dans les ann\u00e9es 1990 chez le fournisseur d\u2019informations financi\u00e8res Fininfo, o\u00f9 ce petit monde officie : Jean-Fran\u00e7ois Rial et Lionel Habasque sont amis depuis la fac et leurs \u00e9tudes de statistiques. L\u2019\u00e9quipe prend son envol \u00e0 partir de 1996 avec l\u2019acquisition de Voyageurs du Monde par Jean-Fran\u00e7ois Rial (Lionel Habasque rejoindra la soci\u00e9t\u00e9<br \/>\nen 2004). En qu\u00eate d\u2019une entreprise \u00e0 reprendre, ce dernier \u00ab flashe \u00bb sur ce petit<br \/>\ntour-op\u00e9rateur de 35 millions d\u2019euros de chiffre d\u2019affaires, dont il est client. Sp\u00e9cialiste du sur-mesure, Voyageurs du Monde intervient \u00e9galement, \u00e0 l\u2019\u00e9poque, dans le vol sec et les circuits accompagn\u00e9s. Ces deux activit\u00e9s sont d\u00e9sormais arr\u00eat\u00e9es.<\/p>\n<p>Deux d\u00e9cennies plus tard, la taille du groupe a \u00e9t\u00e9 multipli\u00e9e par plus de 12. La soci\u00e9t\u00e9, cot\u00e9e \u00e0 Euronext Paris depuis juillet 2006, figure dans le Top 5 des voyagistes fran\u00e7ais, solidement install\u00e9 sur deux des segments de march\u00e9 du voyage les plus porteurs. Il est aussi dot\u00e9 de 16 marques compl\u00e9mentaires, dont 6 principales et une distribution omnicanal \u2013 Web et agences en propre \u2013 totalement int\u00e9gr\u00e9e, qui assure, de longue date, son ind\u00e9pendance et sa libert\u00e9 d\u2019action. S\u2019agissant du Net, la marque Voyageurs du Monde a d\u2019ailleurs lanc\u00e9 mardi un nouveau site, fruit de deux ans de travail.<\/p>\n<p><strong>Mont\u00e9e en puissance<\/strong><\/p>\n<p>Au fil du temps, le p\u00e9rim\u00e8tre du groupe a \u00e9t\u00e9 \u00e9largi et renforc\u00e9 par des acquisitions r\u00e9ussies. La perc\u00e9e dans la \u00ab rando \u00bb et le voyage aventure d\u00e9marre ainsi en 2001 avec la reprise de Terres d\u2019Aventure et s\u2019amplifie, par la suite, avec le rachat, notamment, de Nomade Aventure (2004), de Grand Nord Grand Large (2007), de Chamina-Sylva (2011),tr\u00e8s actif en France, d\u2019Allibert (2012), de La P\u00e8lerine (2014) ou m\u00eame de Loire Valley Travel (2015), un sp\u00e9cialiste de la rando v\u00e9lo dans le Val de Loire. Cette derni\u00e8re acquisition permet \u00e0 la fois de mettre un pied dans le cyclotourisme et de toucher encore davantage la client\u00e8le \u00e9trang\u00e8re.<\/p>\n<p>Car Voyageurs du Monde avait d\u00e9j\u00e0 amorc\u00e9 sa mont\u00e9e en puissance \u00e0 l\u2019international. Il l\u2019avait fait en douceur, en commen\u00e7ant \u00e0 cultiver une client\u00e8le francophone avec l\u2019ouverture d\u2019une agence \u00e0Bruxelles en 2008, puis \u00e0 Gen\u00e8ve, en 2011. La m\u00eame ann\u00e9e, le groupe prend pied au Qu\u00e9bec, gr\u00e2ce \u00e0 l\u2019acquisition d\u2019Uniktour, actif dans le voyage sur mesure et en individuel, une marque en cours de remplacement par la marque Voyageurs du Monde. D\u00e9but 2016, il accentue sa pr\u00e9sence dans la Belle Province avec le rachat, cette fois-ci, d\u2019un expert du voyage aventure, Karavaniers. Avec Loire Valley Travel, Voyageurs du Monde a par ailleurs \u00e9largi son spectre, car sa filiale de cyclotourisme a du succ\u00e8s aupr\u00e8s des Britanniques. Cette client\u00e8le est \u00e9galement vis\u00e9e par les rachats, \u00e0 leur tour amicaux, d\u2019Original Travel et de KE Adventure Travel.<\/p>\n<p>Ce coup d\u2019acc\u00e9l\u00e9rateur sur ce march\u00e9 pr\u00e9sum\u00e9 hautement concurrentiel qu\u2019est la<br \/>\nGrande-Bretagne n\u2019a rien de la folie douce. Bien au contraire. C\u2019est m\u00eame la conclusion d\u2019une intense r\u00e9flexion strat\u00e9gique des dirigeants de Voyageurs du Monde qui a conduit \u00e0 cette offensive. Souhaitant r\u00e9\u00e9quilibrer leur position de leader en France, ils sont partis de deux constats importants.<\/p>\n<p>D\u2019une part, le groupe n\u2019a pas vraiment d\u2019\u00e9quivalent en Europe. D\u2019autre part, le ph\u00e9nom\u00e8ne de \u00ab d\u00e9sinterm\u00e9diation \u00bb, \u00e0 savoir la capacit\u00e9 du consommateur de se fabriquer lui-m\u00eame son voyage \u00e0 forfait sur le Net, n\u2019affecte pas les confr\u00e8res britanniques. Enfin, le d\u00e9veloppement \u00e0 l\u2019international\u00a0 devrait aussi permettre au groupe de mieux vendre la destination France. Une tentative de promotion de celle-ci, lanc\u00e9e aupr\u00e8s des Fran\u00e7ais voil\u00e0 une dizaine d\u2019ann\u00e9es, avait \u00e9t\u00e9 vaine. Avec eux, seule la \u00ab rando \u00bb (Alpes, Pyr\u00e9n\u00e9es, Massif central, calanques\u2026) marche, si l\u2019on peut dire. Le ph\u00e9nom\u00e8ne de soci\u00e9t\u00e9 qu\u2019est la randonn\u00e9e serait tel d\u2019ailleurs que la France des godillots constituerait le premier march\u00e9 du monde !<\/p>\n<p>Avec les Britanniques et autres anglophones, c\u2019est donc une toute autre histoire<br \/>\nque Voyageurs du Monde compte d\u00e9sormais \u00e9crire. Le voyagiste pr\u00e9pare en effet<br \/>\nune offre trekking et v\u00e9lo en France qui leur sera d\u00e9di\u00e9e et qui sera commercialis\u00e9e via un site Internet ad hoc. Mais l\u2019acquisition d\u2019Original Travel et de KE Adventure Travel s\u2019annonce d\u2019autant plus strat\u00e9gique dans l\u2019internationalisation de la PME, sise \u00e0 Paris, que ces tour-op\u00e9rateurs anglais vont lui servir de tremplin pour franchir l\u2019Atlantique et partir \u00e0 la conqu\u00eate des Etats-Unis. D\u2019ici \u00e0 \u00ab <em>deux ou trois ans<\/em> \u00bb, ces marques auront leurs \u00e9quipes locales, sachant que les Am\u00e9ricains repr\u00e9sentent d\u00e9j\u00e0 15 % de leur client\u00e8le. Entre-temps, Voyageurs du Monde aura peut-\u00eatre fait, par ailleurs, un nouveau pas en avant \u2013 voire plusieurs \u2013 sur le Vieux Continent. Sa direction ne cache pas en effet \u00eatre \u00ab en veille \u00bb \u00e0 propos de la<br \/>\nScandinavie et de l\u2019Allemagne, \u00ab<em> un grand pays du v\u00e9lo<\/em> \u00bb. Pas de doute, \u00e7a p\u00e9dale sec chez Voyageurs du Monde !<\/p>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; icon_family=&#8221;none&#8221; text=&#8221;VERSION PDF&#8221; url=&#8221;\/wp-content\/uploads\/2023\/12\/Les-nouveaux-horizons-de-Voyageurs-du-Monde.pdf&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;50px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221;&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[132,143],"tags":[],"class_list":{"0":"post-9729","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-portfolio","7":"category-voyageurs-du-monde-en"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les nouveaux horizons de Voyageurs du Monde - Montefiore Investment<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/montefiore.eu\/en\/les-nouveaux-horizons-de-voyageurs-du-monde\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les nouveaux horizons de Voyageurs du Monde - Montefiore Investment\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;50px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/montefiore.eu\/en\/les-nouveaux-horizons-de-voyageurs-du-monde\/\" \/>\n<meta property=\"og:site_name\" content=\"Montefiore Investment\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-14T10:59:24+00:00\" \/>\n<meta name=\"author\" content=\"Montefiore\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WeAreBlow\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Montefiore\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/les-nouveaux-horizons-de-voyageurs-du-monde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/les-nouveaux-horizons-de-voyageurs-du-monde\\\/\"},\"author\":{\"name\":\"Montefiore\",\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/#\\\/schema\\\/person\\\/67b7c1f31df6e6d86ea1c4793b97a51c\"},\"headline\":\"Les nouveaux horizons de Voyageurs du Monde\",\"datePublished\":\"2018-06-14T10:59:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/les-nouveaux-horizons-de-voyageurs-du-monde\\\/\"},\"wordCount\":1809,\"articleSection\":[\"Portfolio\",\"Voyageurs du monde\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/les-nouveaux-horizons-de-voyageurs-du-monde\\\/\",\"url\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/les-nouveaux-horizons-de-voyageurs-du-monde\\\/\",\"name\":\"Les nouveaux horizons de Voyageurs du Monde - Montefiore Investment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/#website\"},\"datePublished\":\"2018-06-14T10:59:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/#\\\/schema\\\/person\\\/67b7c1f31df6e6d86ea1c4793b97a51c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/les-nouveaux-horizons-de-voyageurs-du-monde\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/montefiore.eu\\\/en\\\/les-nouveaux-horizons-de-voyageurs-du-monde\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/les-nouveaux-horizons-de-voyageurs-du-monde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les nouveaux horizons de Voyageurs du Monde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/\",\"name\":\"Montefiore Investment\",\"description\":\"L&#039;investisseur de r\u00e9f\u00e9rence des PME et ETI de services.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/#\\\/schema\\\/person\\\/67b7c1f31df6e6d86ea1c4793b97a51c\",\"name\":\"Montefiore\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef7f344ce0735d89803a1a87d8ba1b0941d46961f140039710ff76a7be36dd04?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef7f344ce0735d89803a1a87d8ba1b0941d46961f140039710ff76a7be36dd04?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ef7f344ce0735d89803a1a87d8ba1b0941d46961f140039710ff76a7be36dd04?s=96&d=mm&r=g\",\"caption\":\"Montefiore\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/WeAreBlow\"],\"url\":\"https:\\\/\\\/montefiore.eu\\\/en\\\/author\\\/montefiore\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les nouveaux horizons de Voyageurs du Monde - Montefiore Investment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/montefiore.eu\/en\/les-nouveaux-horizons-de-voyageurs-du-monde\/","og_locale":"en_US","og_type":"article","og_title":"Les nouveaux horizons de Voyageurs du Monde - Montefiore Investment","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;50px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221;...","og_url":"https:\/\/montefiore.eu\/en\/les-nouveaux-horizons-de-voyageurs-du-monde\/","og_site_name":"Montefiore Investment","article_published_time":"2018-06-14T10:59:24+00:00","author":"Montefiore","twitter_card":"summary_large_image","twitter_creator":"@WeAreBlow","twitter_misc":{"Written by":"Montefiore","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/montefiore.eu\/en\/les-nouveaux-horizons-de-voyageurs-du-monde\/#article","isPartOf":{"@id":"https:\/\/montefiore.eu\/en\/les-nouveaux-horizons-de-voyageurs-du-monde\/"},"author":{"name":"Montefiore","@id":"https:\/\/montefiore.eu\/en\/#\/schema\/person\/67b7c1f31df6e6d86ea1c4793b97a51c"},"headline":"Les nouveaux horizons de Voyageurs du Monde","datePublished":"2018-06-14T10:59:24+00:00","mainEntityOfPage":{"@id":"https:\/\/montefiore.eu\/en\/les-nouveaux-horizons-de-voyageurs-du-monde\/"},"wordCount":1809,"articleSection":["Portfolio","Voyageurs du monde"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/montefiore.eu\/en\/les-nouveaux-horizons-de-voyageurs-du-monde\/","url":"https:\/\/montefiore.eu\/en\/les-nouveaux-horizons-de-voyageurs-du-monde\/","name":"Les nouveaux horizons de Voyageurs du Monde - Montefiore Investment","isPartOf":{"@id":"https:\/\/montefiore.eu\/en\/#website"},"datePublished":"2018-06-14T10:59:24+00:00","author":{"@id":"https:\/\/montefiore.eu\/en\/#\/schema\/person\/67b7c1f31df6e6d86ea1c4793b97a51c"},"breadcrumb":{"@id":"https:\/\/montefiore.eu\/en\/les-nouveaux-horizons-de-voyageurs-du-monde\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/montefiore.eu\/en\/les-nouveaux-horizons-de-voyageurs-du-monde\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/montefiore.eu\/en\/les-nouveaux-horizons-de-voyageurs-du-monde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/montefiore.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Les nouveaux horizons de Voyageurs du Monde"}]},{"@type":"WebSite","@id":"https:\/\/montefiore.eu\/en\/#website","url":"https:\/\/montefiore.eu\/en\/","name":"Montefiore Investment","description":"L&#039;investisseur de r\u00e9f\u00e9rence des PME et ETI de services.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/montefiore.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/montefiore.eu\/en\/#\/schema\/person\/67b7c1f31df6e6d86ea1c4793b97a51c","name":"Montefiore","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ef7f344ce0735d89803a1a87d8ba1b0941d46961f140039710ff76a7be36dd04?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ef7f344ce0735d89803a1a87d8ba1b0941d46961f140039710ff76a7be36dd04?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ef7f344ce0735d89803a1a87d8ba1b0941d46961f140039710ff76a7be36dd04?s=96&d=mm&r=g","caption":"Montefiore"},"sameAs":["https:\/\/x.com\/WeAreBlow"],"url":"https:\/\/montefiore.eu\/en\/author\/montefiore\/"}]}},"_links":{"self":[{"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/posts\/9729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/comments?post=9729"}],"version-history":[{"count":0,"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/posts\/9729\/revisions"}],"wp:attachment":[{"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/media?parent=9729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/categories?post=9729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montefiore.eu\/en\/wp-json\/wp\/v2\/tags?post=9729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}